{"id":517,"date":"2019-02-05T12:37:09","date_gmt":"2019-02-05T12:37:09","guid":{"rendered":"http:\/\/hr4free.web-romandie.ch\/?p=517"},"modified":"2019-06-28T16:17:17","modified_gmt":"2019-06-28T16:17:17","slug":"redaction-business-plan-resume-operationnel-exemple","status":"publish","type":"post","link":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple","title":{"rendered":"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple"},"content":{"rendered":"<p><em>Cet article fait partie d&rsquo;un dossier complet destin\u00e9 \u00e0 vous aider \u00e0 construire un business plan solide pour votre start up.<\/em><\/p>\n<p><strong>Le r\u00e9sum\u00e9 op\u00e9rationnel fournit un bref aper\u00e7u du but et des objectifs de l&rsquo;entreprise.<\/strong><\/p>\n<p><em>Par Jeff Haden, \u00e9crivain vedette dans les domaines du d\u00e9veloppement personnel et de la gestion de carri\u00e8re et l\u2019auteur du livre \u00ab\u00a0TransForm: Dramatically Improve Your Career, Business, Relationships, and Life: One Simple Step at a Time\u00a0\u00bb.<\/em><\/p>\n<p>S\u2019il peut s\u2019av\u00e9rer difficile de faire tenir un business plan sur une ou deux pages, un r\u00e9sum\u00e9 op\u00e9rationnel percutant pourra pr\u00e9senter bri\u00e8vement les points suivants:<\/p>\n<ul>\n<li>Une br\u00e8ve description des produits et services<\/li>\n<li>Un r\u00e9sum\u00e9 des objectifs<\/li>\n<li>Une description du march\u00e9 bien \u00e9tay\u00e9e<\/li>\n<li>Une argumentation tr\u00e8s pouss\u00e9e concernant la viabilit\u00e9 du mod\u00e8le d\u2019affaires (ceci inclut un examen rapide de la concurrence et de vos avantages comp\u00e9titifs)<\/li>\n<li>Un aper\u00e7u du potentiel de croissance<\/li>\n<li>Une vue d&rsquo;ensemble des besoins de financement<\/li>\n<\/ul>\n<p>Je sais que cela peut sembler requ\u00e9rir beaucoup d\u2019efforts, mais le r\u00e9sum\u00e9 op\u00e9rationnel est souvent la partie d\u00e9cisive de votre business plan.<\/p>\n<p><strong>Une bonne id\u00e9e d\u2019affaires permet en effet de r\u00e9soudre les probl\u00e8mes des clients<\/strong>;<strong>\u00a0<\/strong>si votre r\u00e9sum\u00e9 ne peut pas d\u00e9crire clairement, en une ou deux pages, comment votre affaire va apporter des r\u00e9ponses \u00e0 une probl\u00e9matique particuli\u00e8re et g\u00e9n\u00e9rer un\u00a0<em>b\u00e9n\u00e9fice\u00a0<\/em>pour le client, alors il est tr\u00e8s probable que l\u2019opportunit\u00e9 n\u2019existe pas \u2013 ou alors, la mani\u00e8re dont vous comptez tirer profit d&rsquo;une v\u00e9ritable opportunit\u00e9 n\u2019est pas suffisamment bien d\u00e9finie.<\/p>\n<p>Alors, pensez au r\u00e9sum\u00e9 op\u00e9rationnel comme \u00e0 un aper\u00e7u de votre business plan. \u00c9vitez de le surcharger en essayant de montrer au lecteur combien vos projets sont fascinants, comment vous comptez les mettre en \u0153uvre et \u00e0 quels succ\u00e8s ils vont aboutir.<\/p>\n<h5 style=\"text-align: center;\"><strong>PRATIQUE<\/strong><\/h5>\n<p>\u00c9tant donn\u00e9 qu\u2019un business plan devrait surtout vous aider \u00e0 d\u00e9marrer et faire prosp\u00e9rer votre id\u00e9e d\u2019affaires, votre r\u00e9sum\u00e9 devrait avant tout vous aider \u00e0:<\/p>\n<h5><em>1. Affiner et renforcer votre mod\u00e8le d\u2019affaires<\/em><\/h5>\n<p>Pensez \u00e0 ce r\u00e9sum\u00e9 comme \u00e0 un\u00a0<em>\u00ab\u00a0elevator pitch \u00e9crit\u00a0\u00bb\u00a0<\/em>pour pr\u00e9senter votre mod\u00e8le d\u2019affaires (avec plus de d\u00e9tails, bien s\u00fbr). Votre r\u00e9sum\u00e9 en d\u00e9crira les grandes lignes en se limitant aux points essentiels et en laissant de c\u00f4t\u00e9 les questions annexes et \u00a0les facteurs d\u2019influence secondaires.<\/p>\n<p>Lors de la r\u00e9daction du r\u00e9sum\u00e9 op\u00e9rationnel, vous vous concentrerez naturellement sur les questions peuvent le plus contribuer \u00e0 un \u00e9ventuel succ\u00e8s. Si votre concept est trop flou, trop g\u00e9n\u00e9ral ou trop compliqu\u00e9, revenez en arri\u00e8re et recommencez. La plupart des grandes id\u00e9es d\u2019affaires peuvent \u00eatre d\u00e9crites en quelques phrases seulement.<\/p>\n<h5><em>2. D\u00e9terminer vos priorit\u00e9s<\/em><\/h5>\n<p>Votre synopsis permet au lecteur de se balader \u00e0 travers votre business plan. Quels en sont les \u00e9l\u00e9ments primordiaux? Le d\u00e9veloppement de nouveaux produits? La recherche? Obtenir le site ad\u00e9quat? Nouer des partenariats strat\u00e9giques?<\/p>\n<p>Votre r\u00e9sum\u00e9 peut faire office de guide de r\u00e9daction pour le reste de votre business plan.<\/p>\n<h5><em>3. Jeter les bases du processus complet<\/em><\/h5>\n<p>Une fois votre r\u00e9sum\u00e9 termin\u00e9, vous pouvez l&rsquo;utiliser comme une \u00e9bauche pour le reste de votre plan. \u00c9toffez-en simplement les points essentiels avec plus de d\u00e9tails.<\/p>\n<p>Ensuite, travaillez \u00e0 atteindre votre objectif secondaire en vous concentrant vos lecteurs. M\u00eame si vous cr\u00e9ez un votre business plan uniquement pour votre propre usage, il se peut que vous d\u00e9cidiez \u00e0 un certain moment de rechercher des financements ou de vous associer \u00e0 d\u2019autres investisseurs.<\/p>\n<p>Il faudrait donc faire attention \u00e0 ce que le r\u00e9sum\u00e9 r\u00e9ponde aussi \u00e0 leurs besoins. Mettez-y toute votre \u00e9nergie de mani\u00e8re \u00e0 jeter les bases pour le reste du plan. Que votre enthousiasme pour votre id\u00e9e et votre entreprise puisse rayonner.<\/p>\n<p>En bref, le but est de r\u00e9ussir \u00e0 capter l\u2019attention des lecteurs de sorte \u00e0 ce qu\u2019ils aient envie de continuer \u00e0 lire. Permettez-leur de s\u2019assurer que le contenu du projet correspond \u00e0 leurs attentes en fournissant des descriptions factuelles claires.<\/p>\n<h5 style=\"text-align: center;\"><strong>EXEMPLE<\/strong><\/h5>\n<p>Voici une illustration de\u00a0<a href=\"https:\/\/hr4free.com\/PDF_Files\/Blog_RH_Business_Plan_Exemple_de_resume_operationnel.pdf\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/hr4free.com\/PDF_Files\/Blog_RH_Business_Plan_Exemple_de_resume_operationnel.pdf\"><strong>r\u00e9sum\u00e9 op\u00e9rationnel (exemple)<\/strong><\/a>\u00a0pour le business plan d\u2019un magasin de location de v\u00e9los.<\/p>\n<p>D\u2019une mani\u00e8re g\u00e9n\u00e9rale,\u00a0<strong>si votre entreprise fabrique ou vend des produits, ou fournit diff\u00e9rents types de services, il peut-\u00eatre utile d&rsquo;inclure une section \u00ab\u00a0produits et services\u00a0\u00bb dans votre r\u00e9sum\u00e9 op\u00e9rationnel<\/strong>\u00a0(nous verrons cela dans un article sp\u00e9cifique). Dans le cas pr\u00e9sent, la nature des produits et services offerts est \u00e9vidente; par cons\u00e9quent, inclure une section sp\u00e9cifique e\u00fbt \u00e9t\u00e9 redondant.<\/p>\n<p><em>Traduction par HR4free de l&rsquo;article\u00a0<a href=\"http:\/\/www.inc.com\/jeff-haden\/how-to-write-a-great-business-plan-the-executive-summary.html\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"http:\/\/www.inc.com\/jeff-haden\/how-to-write-a-great-business-plan-the-executive-summary.html\">How to Write a Great Business Plan: The Executive Summary<\/a>\u00a0(en anglais). Reproduit avec la permission de l&rsquo;auteur.<\/em><\/p>\n<p><em>A lire \u00e9galement:<\/em><\/p>\n<ul>\n<li><a href=\"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/Analyse-concurrence-Exercice-Exemple\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/hr4free.com\/fr\/R\u00e9daction-Business-Plan\/Analyse-concurrence-Exercice-Exemple\"><strong>R\u00e9daction du business plan: l&rsquo;analyse concurrentielle<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/%C3%89quipe-de-Direction-Exemple-Plan-de-dotation\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/hr4free.com\/fr\/R\u00e9daction-Business-Plan\/\u00c9quipe-de-Direction-Exemple-Plan-de-dotation\"><strong>R\u00e9daction du business plan: l&rsquo;\u00e9quipe de Direction<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cet article fait partie d&rsquo;un dossier complet destin\u00e9 \u00e0 vous aider \u00e0 construire un business plan solide pour votre start up. Le r\u00e9sum\u00e9 op\u00e9rationnel fournit un bref aper\u00e7u du but et des objectifs de l&rsquo;entreprise. Par Jeff Haden, \u00e9crivain vedette dans les domaines du d\u00e9veloppement personnel et de la gestion de carri\u00e8re et l\u2019auteur du [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[81,79,80],"class_list":["post-517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaction-business-plan","tag-business-model","tag-gestion-dentreprise","tag-marketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple - HR4Free<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple - HR4Free\" \/>\n<meta property=\"og:description\" content=\"Cet article fait partie d&rsquo;un dossier complet destin\u00e9 \u00e0 vous aider \u00e0 construire un business plan solide pour votre start up. Le r\u00e9sum\u00e9 op\u00e9rationnel fournit un bref aper\u00e7u du but et des objectifs de l&rsquo;entreprise. Par Jeff Haden, \u00e9crivain vedette dans les domaines du d\u00e9veloppement personnel et de la gestion de carri\u00e8re et l\u2019auteur du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hr4free.com\/fr\/R\u00e9daction-Business-Plan\/R\u00e9sum\u00e9-op\u00e9rationnel-Exemple\/\" \/>\n<meta property=\"og:site_name\" content=\"HR4Free\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-05T12:37:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-28T16:17:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hr4free.com\/wp-content\/uploads\/2019\/02\/document-3268750_1280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"917\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/#\\\/schema\\\/person\\\/63b4676b4887d228dbc78b611adacc2e\"},\"headline\":\"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple\",\"datePublished\":\"2019-02-05T12:37:09+00:00\",\"dateModified\":\"2019-06-28T16:17:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/\"},\"wordCount\":864,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hr4free.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/document-3268750_1280-1.jpg\",\"keywords\":[\"business model\",\"gestion d'entreprise\",\"marketing\"],\"articleSection\":[\"R\u00e9daction du Business Plan\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/\",\"url\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/\",\"name\":\"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple - HR4Free\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hr4free.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/document-3268750_1280-1.jpg\",\"datePublished\":\"2019-02-05T12:37:09+00:00\",\"dateModified\":\"2019-06-28T16:17:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/#\\\/schema\\\/person\\\/63b4676b4887d228dbc78b611adacc2e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hr4free.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/document-3268750_1280-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hr4free.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/document-3268750_1280-1.jpg\",\"width\":1280,\"height\":917},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/R%C3%A9daction-Business-Plan\\\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/\",\"name\":\"HR4Free\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/#\\\/schema\\\/person\\\/63b4676b4887d228dbc78b611adacc2e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1493e8ac9f7cdeb1d404ed3fa83f9d3a50c10f9a35c09a5271d0ac17a1db68b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1493e8ac9f7cdeb1d404ed3fa83f9d3a50c10f9a35c09a5271d0ac17a1db68b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1493e8ac9f7cdeb1d404ed3fa83f9d3a50c10f9a35c09a5271d0ac17a1db68b2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/hr4free.com\\\/fr\\\/author\\\/held\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple - HR4Free","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple - HR4Free","og_description":"Cet article fait partie d&rsquo;un dossier complet destin\u00e9 \u00e0 vous aider \u00e0 construire un business plan solide pour votre start up. Le r\u00e9sum\u00e9 op\u00e9rationnel fournit un bref aper\u00e7u du but et des objectifs de l&rsquo;entreprise. Par Jeff Haden, \u00e9crivain vedette dans les domaines du d\u00e9veloppement personnel et de la gestion de carri\u00e8re et l\u2019auteur du [&hellip;]","og_url":"https:\/\/hr4free.com\/fr\/R\u00e9daction-Business-Plan\/R\u00e9sum\u00e9-op\u00e9rationnel-Exemple\/","og_site_name":"HR4Free","article_published_time":"2019-02-05T12:37:09+00:00","article_modified_time":"2019-06-28T16:17:17+00:00","og_image":[{"width":1280,"height":917,"url":"https:\/\/hr4free.com\/wp-content\/uploads\/2019\/02\/document-3268750_1280-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#article","isPartOf":{"@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/"},"author":{"name":"admin","@id":"https:\/\/hr4free.com\/fr\/#\/schema\/person\/63b4676b4887d228dbc78b611adacc2e"},"headline":"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple","datePublished":"2019-02-05T12:37:09+00:00","dateModified":"2019-06-28T16:17:17+00:00","mainEntityOfPage":{"@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/"},"wordCount":864,"commentCount":0,"image":{"@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#primaryimage"},"thumbnailUrl":"https:\/\/hr4free.com\/wp-content\/uploads\/2019\/02\/document-3268750_1280-1.jpg","keywords":["business model","gestion d'entreprise","marketing"],"articleSection":["R\u00e9daction du Business Plan"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/","url":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/","name":"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple - HR4Free","isPartOf":{"@id":"https:\/\/hr4free.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#primaryimage"},"image":{"@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#primaryimage"},"thumbnailUrl":"https:\/\/hr4free.com\/wp-content\/uploads\/2019\/02\/document-3268750_1280-1.jpg","datePublished":"2019-02-05T12:37:09+00:00","dateModified":"2019-06-28T16:17:17+00:00","author":{"@id":"https:\/\/hr4free.com\/fr\/#\/schema\/person\/63b4676b4887d228dbc78b611adacc2e"},"breadcrumb":{"@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#primaryimage","url":"https:\/\/hr4free.com\/wp-content\/uploads\/2019\/02\/document-3268750_1280-1.jpg","contentUrl":"https:\/\/hr4free.com\/wp-content\/uploads\/2019\/02\/document-3268750_1280-1.jpg","width":1280,"height":917},{"@type":"BreadcrumbList","@id":"https:\/\/hr4free.com\/fr\/R%C3%A9daction-Business-Plan\/R%C3%A9sum%C3%A9-op%C3%A9rationnel-Exemple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hr4free.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9daction du business plan: le r\u00e9sum\u00e9 op\u00e9rationnel \u2013 Exemple"}]},{"@type":"WebSite","@id":"https:\/\/hr4free.com\/fr\/#website","url":"https:\/\/hr4free.com\/fr\/","name":"HR4Free","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hr4free.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/hr4free.com\/fr\/#\/schema\/person\/63b4676b4887d228dbc78b611adacc2e","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1493e8ac9f7cdeb1d404ed3fa83f9d3a50c10f9a35c09a5271d0ac17a1db68b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1493e8ac9f7cdeb1d404ed3fa83f9d3a50c10f9a35c09a5271d0ac17a1db68b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1493e8ac9f7cdeb1d404ed3fa83f9d3a50c10f9a35c09a5271d0ac17a1db68b2?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/hr4free.com\/fr\/author\/held\/"}]}},"_links":{"self":[{"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/posts\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":3,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/posts\/517\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/posts\/517\/revisions\/643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/media\/743"}],"wp:attachment":[{"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/media?parent=517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/categories?post=517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hr4free.com\/fr\/wp-json\/wp\/v2\/tags?post=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}